{"id":170,"date":"2002-02-25T12:31:14","date_gmt":"2002-02-25T11:31:14","guid":{"rendered":"http:\/\/relaunch2022.schwieger-architekten.de\/?post_type=portfolio&#038;p=170"},"modified":"2023-06-05T10:37:35","modified_gmt":"2023-06-05T08:37:35","slug":"nachbarschaftszentrum-grone","status":"publish","type":"portfolio","link":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/","title":{"rendered":"Nachbarschaftszentrum Grone"},"content":{"rendered":"<div  id=\"ProjectHeaderContainer\"  class='flex_column av-p11mq-7571cca12f8723a761eb33816c10981f av_one_full  avia-builder-el-0  el_before_av_hr  avia-builder-el-first  first flex_column_div  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3l9wuxv-facd7445af5b27571baef4c4bbfdf8ce\">\n#top .av-special-heading.av-l3l9wuxv-facd7445af5b27571baef4c4bbfdf8ce{\npadding-bottom:10px;\n}\nbody .av-special-heading.av-l3l9wuxv-facd7445af5b27571baef4c4bbfdf8ce .av-special-heading-tag .heading-char{\nfont-size:25px;\n}\n.av-special-heading.av-l3l9wuxv-facd7445af5b27571baef4c4bbfdf8ce .av-subheading{\nfont-size:15px;\n}\n<\/style>\n<div  id=\"ProjectHeader\"  class='av-special-heading av-l3l9wuxv-facd7445af5b27571baef4c4bbfdf8ce av-special-heading-h1 blockquote modern-quote  avia-builder-el-1  el_before_av_textblock  avia-builder-el-first '><h1 class='av-special-heading-tag '  itemprop=\"headline\"  >Nachbarschaftszentrum Grone<\/h1><div class='av-subheading av-subheading_below'><p>Workshop 1.Preis und Realisierung<br \/>\nStadt G\u00f6ttingen<\/p>\n<\/div><div class=\"special-heading-border\"><div class=\"special-heading-inner-border\"><\/div><\/div><\/div><br \/>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3l9zimx-f5193e2ba4d0d85cdb2bde1ca0256b72\">\n#top .av_textblock_section.av-l3l9zimx-f5193e2ba4d0d85cdb2bde1ca0256b72 .avia_textblock{\ntext-align:justify;\n}\n<\/style>\n<section  class='av_textblock_section av-l3l9zimx-f5193e2ba4d0d85cdb2bde1ca0256b72 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Das Grundst\u00fcck ist eine gr\u00fcne Oase innerhalb der Bebauung. Die Qualit\u00e4ten des Grundst\u00fcckes werden genutzt: Das neue Geb\u00e4ude hat einen geschlossenen,die Nebenr\u00e4ume aufnehmenden &#8222;R\u00fccken&#8220; und die sich nach S\u00fcdwesten \u00f6ffnenden Gruppen- und Gemeinschaftsr\u00e4ume. Alle Gemeinschaftsr\u00e4ume sind zum Gr\u00fcnbereich hin orientiert mit vorgelagerten Terrassen. Die Verbindung zur Jona-Gemeinde wird durch einen baumbestandenen Platz hergestellt.<\/p>\n<p>Unter einem gemeinsamen Dach werden R\u00e4ume mit unterschiedlichsten Anforderungen organisiert. Dies spiegelt sich sowohl in der Grundrissorganisation als auch in der Fassade wieder. Ein Holzskelett mit Fachwerkbindern und Pfetten tr\u00e4gt das Dach.<\/p>\n<\/div><\/section><\/p><\/div>\n\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3la0mcf-1fe90eb1152fa5c5f6e62306a5d2875b\">\n#top .hr.hr-invisible.av-l3la0mcf-1fe90eb1152fa5c5f6e62306a5d2875b{\nheight:50px;\n}\n<\/style>\n<div  class='hr av-l3la0mcf-1fe90eb1152fa5c5f6e62306a5d2875b hr-invisible  avia-builder-el-3  el_after_av_one_full  el_before_av_one_full '><span class='hr-inner '><span class=\"hr-inner-style\"><\/span><\/span><\/div>\n<div class='flex_column_table av-n6lnm-a136a985af9216a4eb93e39042f4244d sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-n6lnm-a136a985af9216a4eb93e39042f4244d\">\n#top .flex_column_table.av-equal-height-column-flextable.av-n6lnm-a136a985af9216a4eb93e39042f4244d{\nmargin-top:0px;\nmargin-bottom:1%;\n}\n.flex_column.av-n6lnm-a136a985af9216a4eb93e39042f4244d{\nwidth:100%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-n6lnm-a136a985af9216a4eb93e39042f4244d .av-flex-placeholder{\nwidth:0%;\n}\n<\/style>\n<div  class='flex_column av-n6lnm-a136a985af9216a4eb93e39042f4244d av_one_full  avia-builder-el-4  el_after_av_hr  el_before_av_one_full  first flex_column_table_cell av-equal-height-column av-align-middle  '     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3l9xgta-97cb713c77afcec00ae0ea271045eb25\">\n.avia-image-container.av-l3l9xgta-97cb713c77afcec00ae0ea271045eb25 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l3l9xgta-97cb713c77afcec00ae0ea271045eb25 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l3l9xgta-97cb713c77afcec00ae0ea271045eb25 av-styling-no-styling av-img-linked avia-align-center  avia-builder-el-5  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1030x343.jpg\" data-srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1030x343.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-400x133.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-768x256.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1536x512.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1500x500.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-705x235.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-450x150.jpg 450w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-360x120.jpg 360w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1.jpg 1600w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Nachbarschaftszentrum Grone'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2800 avia-img-lazy-loading-not-2800 avia_image ' src=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1030x343.jpg\" alt='Nachbarschaftszentrum Grone' title='Nachbarschaftszentrum Grone'  height=\"343\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1030x343.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-400x133.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-768x256.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1536x512.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-1500x500.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-705x235.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-450x150.jpg 450w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1-360x120.jpg 360w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-ansicht-sued-1.jpg 1600w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-l3l9xlg8-0027ef95ae5ebb999ad9231a50e6da2a '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Ansicht S\u00fcd<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-1cnoa-23d442241cc798eca6ca80cf588bf727 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-1cnoa-23d442241cc798eca6ca80cf588bf727\">\n#top .flex_column_table.av-equal-height-column-flextable.av-1cnoa-23d442241cc798eca6ca80cf588bf727{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.flex_column.av-1cnoa-23d442241cc798eca6ca80cf588bf727{\nwidth:100%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-1cnoa-23d442241cc798eca6ca80cf588bf727 .av-flex-placeholder{\nwidth:0%;\n}\n<\/style>\n<div  class='flex_column av-1cnoa-23d442241cc798eca6ca80cf588bf727 av_one_full  avia-builder-el-7  el_after_av_one_full  el_before_av_one_full  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3l9y2eq-c920be58bc5c8312f896456038444fec\">\n.avia-image-container.av-l3l9y2eq-c920be58bc5c8312f896456038444fec img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l3l9y2eq-c920be58bc5c8312f896456038444fec .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l3l9y2eq-c920be58bc5c8312f896456038444fec av-styling-no-styling av-img-linked avia-align-center  avia-builder-el-8  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1030x343.jpg\" data-srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1030x343.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-400x133.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-768x256.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1536x512.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1500x500.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-705x235.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-450x150.jpg 450w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-360x120.jpg 360w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west.jpg 1600w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Nachbarschaftszentrum Grone'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2796 avia-img-lazy-loading-not-2796 avia_image ' src=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1030x343.jpg\" alt='Nachbarschaftszentrum Grone' title='Nachbarschaftszentrum Grone'  height=\"343\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1030x343.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-400x133.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-768x256.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1536x512.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-1500x500.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-705x235.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-450x150.jpg 450w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west-360x120.jpg 360w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-west.jpg 1600w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-l3l9y89p-65a75d7b01ed106975660ed2948ba986 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Ansicht West<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-7tbg2-1b9b9d55c8bdc7d418a95ff172743529 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-7tbg2-1b9b9d55c8bdc7d418a95ff172743529\">\n#top .flex_column_table.av-equal-height-column-flextable.av-7tbg2-1b9b9d55c8bdc7d418a95ff172743529{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.flex_column.av-7tbg2-1b9b9d55c8bdc7d418a95ff172743529{\nwidth:100%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-7tbg2-1b9b9d55c8bdc7d418a95ff172743529 .av-flex-placeholder{\nwidth:0%;\n}\n<\/style>\n<div  class='flex_column av-7tbg2-1b9b9d55c8bdc7d418a95ff172743529 av_one_full  avia-builder-el-10  el_after_av_one_full  el_before_av_one_full  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3l9yib9-48505113edafef44c3bf9607f2a4bb4f\">\n.avia-image-container.av-l3l9yib9-48505113edafef44c3bf9607f2a4bb4f img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l3l9yib9-48505113edafef44c3bf9607f2a4bb4f .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l3l9yib9-48505113edafef44c3bf9607f2a4bb4f av-styling-no-styling av-img-linked avia-align-center  avia-builder-el-11  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1030x486.jpg\" data-srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1030x486.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-400x189.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-768x362.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1536x724.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1500x707.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-705x332.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-318x150.jpg 318w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-254x120.jpg 254w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1.jpg 1584w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Nachbarschaftszentrum Grone'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2798 avia-img-lazy-loading-not-2798 avia_image ' src=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1030x486.jpg\" alt='Nachbarschaftszentrum Grone' title='Nachbarschaftszentrum Grone'  height=\"486\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1030x486.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-400x189.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-768x362.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1536x724.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-1500x707.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-705x332.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-318x150.jpg 318w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1-254x120.jpg 254w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-grundriss-1.jpg 1584w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-l3l9ymkb-d39366b4d6887d99923d560af01954ab '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Grundriss<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-q4pve-880f5a752c1aee1c0316aa5a2b0f2bb9 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-q4pve-880f5a752c1aee1c0316aa5a2b0f2bb9\">\n#top .flex_column_table.av-equal-height-column-flextable.av-q4pve-880f5a752c1aee1c0316aa5a2b0f2bb9{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.flex_column.av-q4pve-880f5a752c1aee1c0316aa5a2b0f2bb9{\nwidth:100%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-q4pve-880f5a752c1aee1c0316aa5a2b0f2bb9 .av-flex-placeholder{\nwidth:0%;\n}\n<\/style>\n<div  class='flex_column av-q4pve-880f5a752c1aee1c0316aa5a2b0f2bb9 av_one_full  avia-builder-el-13  el_after_av_one_full  el_before_av_one_full  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3la93ob-0ee016c6938ede4b26a5eb4b0af99844\">\n.avia-image-container.av-l3la93ob-0ee016c6938ede4b26a5eb4b0af99844 img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l3la93ob-0ee016c6938ede4b26a5eb4b0af99844 .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l3la93ob-0ee016c6938ede4b26a5eb4b0af99844 av-styling-no-styling av-img-linked avia-align-center  avia-builder-el-14  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1030x606.jpg\" data-srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1030x606.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-400x236.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-768x452.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-204x120.jpg 204w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1536x904.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1500x883.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-705x415.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-255x150.jpg 255w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1.jpg 1600w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Nachbarschaftszentrum Grone'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2806 avia-img-lazy-loading-not-2806 avia_image ' src=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1030x606.jpg\" alt='Nachbarschaftszentrum Grone' title='Nachbarschaftszentrum Grone'  height=\"606\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1030x606.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-400x236.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-768x452.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-204x120.jpg 204w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1536x904.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-1500x883.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-705x415.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1-255x150.jpg 255w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-04-1.jpg 1600w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-l3la978x-54f5193c2768f7b34ae4554605bd139f '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Von S\u00fcdosten<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-jwhca-f755de38b2df2aa1aaf53d02a1d410cc sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-jwhca-f755de38b2df2aa1aaf53d02a1d410cc\">\n#top .flex_column_table.av-equal-height-column-flextable.av-jwhca-f755de38b2df2aa1aaf53d02a1d410cc{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.flex_column.av-jwhca-f755de38b2df2aa1aaf53d02a1d410cc{\nwidth:100%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-jwhca-f755de38b2df2aa1aaf53d02a1d410cc .av-flex-placeholder{\nwidth:0%;\n}\n<\/style>\n<div  class='flex_column av-jwhca-f755de38b2df2aa1aaf53d02a1d410cc av_one_full  avia-builder-el-16  el_after_av_one_full  el_before_av_one_full  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3la9jxd-0974e176640753a99fb5f9b7356fd8fb\">\n.avia-image-container.av-l3la9jxd-0974e176640753a99fb5f9b7356fd8fb img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l3la9jxd-0974e176640753a99fb5f9b7356fd8fb .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l3la9jxd-0974e176640753a99fb5f9b7356fd8fb av-styling-no-styling av-img-linked avia-align-center  avia-builder-el-17  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1030x590.jpg\" data-srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1030x590.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-400x229.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-768x440.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-700x400.jpg 700w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1536x880.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1500x860.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-705x404.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-262x150.jpg 262w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-209x120.jpg 209w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1.jpg 1600w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Nachbarschaftszentrum Grone'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2808 avia-img-lazy-loading-not-2808 avia_image ' src=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1030x590.jpg\" alt='Nachbarschaftszentrum Grone' title='Nachbarschaftszentrum Grone'  height=\"590\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1030x590.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-400x229.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-768x440.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-700x400.jpg 700w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1536x880.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-1500x860.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-705x404.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-262x150.jpg 262w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1-209x120.jpg 209w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-03-1.jpg 1600w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-l3la9np5-7e73ba245a830b418c631b1e8830b337 '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Von Osten<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-gto56-0e16a20c069240d5d40ca19893662f54 sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-gto56-0e16a20c069240d5d40ca19893662f54\">\n#top .flex_column_table.av-equal-height-column-flextable.av-gto56-0e16a20c069240d5d40ca19893662f54{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.flex_column.av-gto56-0e16a20c069240d5d40ca19893662f54{\nwidth:100%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-gto56-0e16a20c069240d5d40ca19893662f54 .av-flex-placeholder{\nwidth:0%;\n}\n<\/style>\n<div  class='flex_column av-gto56-0e16a20c069240d5d40ca19893662f54 av_one_full  avia-builder-el-19  el_after_av_one_full  el_before_av_one_full  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3laa2tk-bb0ea5c7708cec269269017ba76ab4da\">\n.avia-image-container.av-l3laa2tk-bb0ea5c7708cec269269017ba76ab4da img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l3laa2tk-bb0ea5c7708cec269269017ba76ab4da .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l3laa2tk-bb0ea5c7708cec269269017ba76ab4da av-styling-no-styling av-img-linked avia-align-center  avia-builder-el-20  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1030x773.jpg\" data-srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1030x773.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-400x300.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-768x576.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1536x1152.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1500x1125.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-705x529.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-200x150.jpg 200w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-160x120.jpg 160w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05.jpg 1600w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='Nachbarschaftszentrum Grone'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2804 avia-img-lazy-loading-not-2804 avia_image ' src=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1030x773.jpg\" alt='Nachbarschaftszentrum Grone' title='Nachbarschaftszentrum Grone'  height=\"773\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1030x773.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-400x300.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-768x576.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1536x1152.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-1500x1125.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-705x529.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-200x150.jpg 200w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05-160x120.jpg 160w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-05.jpg 1600w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-l3la9ur1-b4bdcb5e37ab9dd84383a59484a6cfdb '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Flur<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><div class='flex_column_table av-2lhu-37ad66b80e441e186a9353967ad6f6ef sc-av_one_full av-equal-height-column-flextable'>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-2lhu-37ad66b80e441e186a9353967ad6f6ef\">\n#top .flex_column_table.av-equal-height-column-flextable.av-2lhu-37ad66b80e441e186a9353967ad6f6ef{\nmargin-top:10px;\nmargin-bottom:10px;\n}\n.flex_column.av-2lhu-37ad66b80e441e186a9353967ad6f6ef{\nwidth:100%;\nmargin-left:0;\n}\n#top .flex_column_table.av-equal-height-column-flextable.av-2lhu-37ad66b80e441e186a9353967ad6f6ef .av-flex-placeholder{\nwidth:0%;\n}\n<\/style>\n<div  class='flex_column av-2lhu-37ad66b80e441e186a9353967ad6f6ef av_one_full  avia-builder-el-22  el_after_av_one_full  avia-builder-el-last  first flex_column_table_cell av-equal-height-column av-align-middle  column-top-margin'     ><p>\n<style type=\"text\/css\" data-created_by=\"avia_inline_auto\" id=\"style-css-av-l3laaasl-3cabca28cce6af4bf0f46bad13a2621b\">\n.avia-image-container.av-l3laaasl-3cabca28cce6af4bf0f46bad13a2621b img.avia_image{\nbox-shadow:none;\n}\n.avia-image-container.av-l3laaasl-3cabca28cce6af4bf0f46bad13a2621b .av-image-caption-overlay-center{\ncolor:#ffffff;\n}\n<\/style>\n<div  class='avia-image-container av-l3laaasl-3cabca28cce6af4bf0f46bad13a2621b av-styling-no-styling av-img-linked avia-align-center  avia-builder-el-23  el_before_av_textblock  avia-builder-el-first '   itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\" ><div class=\"avia-image-container-inner\"><div class=\"avia-image-overlay-wrap\"><a href=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1030x606.jpg\" data-srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1030x606.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-400x235.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-768x452.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-204x120.jpg 204w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1536x903.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1500x882.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-705x415.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-255x150.jpg 255w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06.jpg 1600w\" data-sizes=\"(max-width: 1030px) 100vw, 1030px\" class='avia_image '  aria-label='nachbarschaftszentrum-grone-06'><img decoding=\"async\" fetchpriority=\"high\" class='wp-image-2802 avia-img-lazy-loading-not-2802 avia_image ' src=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1030x606.jpg\" alt='' title='nachbarschaftszentrum-grone-06'  height=\"606\" width=\"1030\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1030x606.jpg 1030w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-400x235.jpg 400w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-768x452.jpg 768w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-204x120.jpg 204w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1536x903.jpg 1536w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-1500x882.jpg 1500w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-705x415.jpg 705w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06-255x150.jpg 255w, https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone-06.jpg 1600w\" sizes=\"(max-width: 1030px) 100vw, 1030px\" \/><\/a><\/div><\/div><\/div><br \/>\n<section  class='av_textblock_section av-l3laaenf-3a8a649cf5a76f476e06a45b05880b5c '   itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/CreativeWork\" ><div class='avia_textblock'  itemprop=\"text\" ><p>Von Nordwesten<\/p>\n<\/div><\/section><\/p><\/div><\/div><!--close column table wrapper. Autoclose: 1 --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Workshop 1.Preis und Realisierung<br \/>\nStadt G\u00f6ttingen<\/p>\n","protected":false},"author":1,"featured_media":2794,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"tags":[],"portfolio_entries":[18],"class_list":["post-170","portfolio","type-portfolio","status-publish","has-post-thumbnail","hentry","portfolio_entries-bauten-fuer-gemeinschaft-oeffentliche-bauten"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachbarschaftszentrum Grone | Schwieger Architekten G\u00f6ttingen<\/title>\n<meta name=\"description\" content=\"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachbarschaftszentrum Grone | Schwieger Architekten G\u00f6ttingen\" \/>\n<meta property=\"og:description\" content=\"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/\" \/>\n<meta property=\"og:site_name\" content=\"Schwieger Architekten\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-05T08:37:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"600\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/\",\"url\":\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/\",\"name\":\"Nachbarschaftszentrum Grone | Schwieger Architekten G\u00f6ttingen\",\"isPartOf\":{\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg\",\"datePublished\":\"2002-02-25T11:31:14+00:00\",\"dateModified\":\"2023-06-05T08:37:35+00:00\",\"description\":\"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#primaryimage\",\"url\":\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg\",\"contentUrl\":\"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg\",\"width\":900,\"height\":600,\"caption\":\"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.schwieger-architekten.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachbarschaftszentrum Grone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.schwieger-architekten.de\/de\/#website\",\"url\":\"https:\/\/www.schwieger-architekten.de\/de\/\",\"name\":\"Schwieger Architekten\",\"description\":\"Schwieger Architekten G\u00f6ttingen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.schwieger-architekten.de\/de\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachbarschaftszentrum Grone | Schwieger Architekten G\u00f6ttingen","description":"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/","og_locale":"de_DE","og_type":"article","og_title":"Nachbarschaftszentrum Grone | Schwieger Architekten G\u00f6ttingen","og_description":"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen.","og_url":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/","og_site_name":"Schwieger Architekten","article_modified_time":"2023-06-05T08:37:35+00:00","og_image":[{"width":900,"height":600,"url":"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/","url":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/","name":"Nachbarschaftszentrum Grone | Schwieger Architekten G\u00f6ttingen","isPartOf":{"@id":"https:\/\/www.schwieger-architekten.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#primaryimage"},"image":{"@id":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg","datePublished":"2002-02-25T11:31:14+00:00","dateModified":"2023-06-05T08:37:35+00:00","description":"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen.","breadcrumb":{"@id":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#primaryimage","url":"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg","contentUrl":"https:\/\/www.schwieger-architekten.de\/wp-content\/uploads\/2002\/02\/nachbarschaftszentrum-grone.jpg","width":900,"height":600,"caption":"1. Preis im Workshop und Realisierung des Neubau f\u00fcr das Nachbarschaftszentrum Grone durch Schwieger Architekten in G\u00f6ttingen."},{"@type":"BreadcrumbList","@id":"https:\/\/www.schwieger-architekten.de\/de\/projekt\/nachbarschaftszentrum-grone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.schwieger-architekten.de\/de\/"},{"@type":"ListItem","position":2,"name":"Nachbarschaftszentrum Grone"}]},{"@type":"WebSite","@id":"https:\/\/www.schwieger-architekten.de\/de\/#website","url":"https:\/\/www.schwieger-architekten.de\/de\/","name":"Schwieger Architekten","description":"Schwieger Architekten G\u00f6ttingen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.schwieger-architekten.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/portfolio\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/portfolio"}],"about":[{"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/types\/portfolio"}],"author":[{"embeddable":true,"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":8,"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/portfolio\/170\/revisions"}],"predecessor-version":[{"id":2810,"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/portfolio\/170\/revisions\/2810"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/media\/2794"}],"wp:attachment":[{"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/media?parent=170"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/tags?post=170"},{"taxonomy":"portfolio_entries","embeddable":true,"href":"https:\/\/www.schwieger-architekten.de\/de\/wp-json\/wp\/v2\/portfolio_entries?post=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}